{"id":9883,"date":"2023-08-24T16:57:05","date_gmt":"2023-08-24T13:57:05","guid":{"rendered":"https:\/\/e-kalastus.ee\/toode\/cheburaska-wolfram-1g-1tk\/"},"modified":"2026-04-16T15:34:36","modified_gmt":"2026-04-16T12:34:36","slug":"cheburaska-wolfram-1g-1tk","status":"publish","type":"product","link":"https:\/\/e-kalastus.ee\/en\/products\/tungsten-cheburashka-1g-1pc\/","title":{"rendered":"Tungsten Cheburashka 1g 1pc"},"content":{"rendered":"\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":67160,"template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[1167],"product_tag":[],"class_list":{"0":"post-9883","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-volfram","7":"pa_kaal-0-15-4-5g","9":"first","10":"instock","11":"sale","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"uagb_featured_image_src":{"full":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/tungsten-cheburashka-gewichte-plain-sinker.jpg",800,800,false],"thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/tungsten-cheburashka-gewichte-plain-sinker-150x150.jpg",150,150,true],"medium":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/tungsten-cheburashka-gewichte-plain-sinker-300x300.jpg",300,300,true],"medium_large":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/tungsten-cheburashka-gewichte-plain-sinker-768x768.jpg",768,768,true],"large":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/tungsten-cheburashka-gewichte-plain-sinker-800x800.jpg",800,800,true],"1536x1536":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/tungsten-cheburashka-gewichte-plain-sinker.jpg",800,800,false],"2048x2048":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/tungsten-cheburashka-gewichte-plain-sinker.jpg",800,800,false],"woocommerce_thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/tungsten-cheburashka-gewichte-plain-sinker-768x768.jpg",324,324,true],"woocommerce_single":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/tungsten-cheburashka-gewichte-plain-sinker-768x768.jpg",416,416,true],"woocommerce_gallery_thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/tungsten-cheburashka-gewichte-plain-sinker-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"adam.mrozek","author_link":"https:\/\/e-kalastus.ee\/en\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/product\/9883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/media\/67160"}],"wp:attachment":[{"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/media?parent=9883"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/product_brand?post=9883"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/product_cat?post=9883"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/product_tag?post=9883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}