{"id":15939,"date":"2023-09-09T13:02:06","date_gmt":"2023-09-09T10:02:06","guid":{"rendered":"https:\/\/e-kalastus.ee\/toode\/voobler-abu-carsia-tormentor-f-7cm-9g-gp\/"},"modified":"2026-05-08T03:01:11","modified_gmt":"2026-05-08T00:01:11","slug":"voobler-abu-carsia-tormentor-f-7cm-9g-gp-2","status":"publish","type":"product","link":"https:\/\/e-kalastus.ee\/toode\/voobler-abu-carsia-tormentor-f-7cm-9g-gp-2\/","title":{"rendered":"Abu Garcia Tormentor F 7cm 9g 0,3-0,6m #GP"},"content":{"rendered":"\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":68910,"template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[766],"product_cat":[1475],"product_tag":[],"class_list":{"0":"post-15939","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-abu-garcia","7":"product_cat-muud-voblerid-voblerid","8":"pa_brand-abu-garcia","9":"pa_kaal-7-13-9g","10":"pa_pikkus-7-11-9cm","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"uagb_featured_image_src":{"full":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/images-864.jpg",387,130,false],"thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/images-864-150x150.jpg",150,150,true],"medium":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/images-864-300x300.jpg",300,300,true],"medium_large":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/images-864-768x768.jpg",768,768,true],"large":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/images-864-800x800.jpg",800,800,true],"1536x1536":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/images-864.jpg",387,130,false],"2048x2048":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/images-864.jpg",387,130,false],"woocommerce_thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/images-864-768x768.jpg",324,324,true],"woocommerce_single":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/images-864.jpg",387,130,false],"woocommerce_gallery_thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/images-864-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"adam.mrozek","author_link":"https:\/\/e-kalastus.ee\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product\/15939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/media\/68910"}],"wp:attachment":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/media?parent=15939"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product_brand?post=15939"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product_cat?post=15939"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product_tag?post=15939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}