{"id":1106,"date":"2023-08-09T13:11:34","date_gmt":"2023-08-09T10:11:34","guid":{"rendered":"https:\/\/e-kalastus.ee\/toode\/feeder-akara-fish-point-39m-test-120g\/"},"modified":"2026-04-16T16:27:14","modified_gmt":"2026-04-16T13:27:14","slug":"feeder-akara-fish-point-39m-test-120g-2","status":"publish","type":"product","link":"https:\/\/e-kalastus.ee\/toode\/feeder-akara-fish-point-39m-test-120g-2\/","title":{"rendered":"Akara Fish Point 3,9m test 120g"},"content":{"rendered":"\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":69889,"template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[915],"product_cat":[15],"product_tag":[],"class_list":{"0":"post-1106","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-akara","7":"product_cat-maaramata","8":"product_shipping_class-suur","9":"pa_brand-akara","10":"pa_pikkus-3-m","11":"pa_test-100-120g","13":"first","14":"outofstock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"uagb_featured_image_src":{"full":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/akara-fish-point-tx-20.jpg",600,600,false],"thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/akara-fish-point-tx-20-150x150.jpg",150,150,true],"medium":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/akara-fish-point-tx-20-300x300.jpg",300,300,true],"medium_large":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/akara-fish-point-tx-20-768x768.jpg",768,768,true],"large":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/akara-fish-point-tx-20-800x800.jpg",800,800,true],"1536x1536":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/akara-fish-point-tx-20.jpg",600,600,false],"2048x2048":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/akara-fish-point-tx-20.jpg",600,600,false],"woocommerce_thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/akara-fish-point-tx-20-768x768.jpg",324,324,true],"woocommerce_single":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/akara-fish-point-tx-20-768x768.jpg",416,416,true],"woocommerce_gallery_thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/akara-fish-point-tx-20-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"adam.mrozek","author_link":"https:\/\/e-kalastus.ee\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product\/1106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/media\/69889"}],"wp:attachment":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/media?parent=1106"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product_brand?post=1106"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product_cat?post=1106"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product_tag?post=1106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}