{"id":46392,"date":"2024-01-16T20:23:17","date_gmt":"2024-01-16T18:23:17","guid":{"rendered":"https:\/\/e-kalastus.ee\/toode\/landikarp-iron-wolf-dez-044-o-22517550cm\/"},"modified":"2026-04-16T15:59:30","modified_gmt":"2026-04-16T12:59:30","slug":"landikarp-iron-wolf-dez-044-o-22517550cm","status":"publish","type":"product","link":"https:\/\/e-kalastus.ee\/toode\/landikarp-iron-wolf-dez-044-o-22517550cm\/","title":{"rendered":"Landikarp Iron Wolf DEZ-044-O 22,5*17,5*5,0cm"},"content":{"rendered":"\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":46391,"template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[1195],"product_tag":[],"class_list":{"0":"post-46392","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-karbid","8":"first","9":"instock","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"uagb_featured_image_src":{"full":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/01\/DEZ-044-O.jpg",1000,1000,false],"thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/01\/DEZ-044-O-150x150.jpg",150,150,true],"medium":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/01\/DEZ-044-O-300x300.jpg",300,300,true],"medium_large":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/01\/DEZ-044-O-768x768.jpg",768,768,true],"large":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/01\/DEZ-044-O-800x800.jpg",800,800,true],"1536x1536":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/01\/DEZ-044-O.jpg",1000,1000,false],"2048x2048":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/01\/DEZ-044-O.jpg",1000,1000,false],"woocommerce_thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/01\/DEZ-044-O-768x768.jpg",324,324,true],"woocommerce_single":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/01\/DEZ-044-O-768x768.jpg",416,416,true],"woocommerce_gallery_thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/01\/DEZ-044-O-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"adam.mrozek","author_link":"https:\/\/e-kalastus.ee\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product\/46392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/media\/46391"}],"wp:attachment":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/media?parent=46392"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product_brand?post=46392"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product_cat?post=46392"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product_tag?post=46392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}