{"id":132491,"date":"2026-03-24T15:10:57","date_gmt":"2026-03-24T13:10:57","guid":{"rendered":"https:\/\/e-kalastus.ee\/toode\/spinnaputukad-lant-v2-0-roosa\/"},"modified":"2026-04-16T16:46:19","modified_gmt":"2026-04-16T13:46:19","slug":"spinnaputukad-lant-v2-0-roosa","status":"publish","type":"product","link":"https:\/\/e-kalastus.ee\/en\/products\/spinning-lure-v2-0-pink\/","title":{"rendered":"Spinning Lure v2.0 #Pink"},"content":{"rendered":"\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":132490,"template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[1511],"product_tag":[],"class_list":{"0":"post-132491","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-spinnaputukad-kasitoo","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"uagb_featured_image_src":{"full":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2026\/03\/image-47677.png",1000,666,false],"thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2026\/03\/image-47677-150x150.png",150,150,true],"medium":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2026\/03\/image-47677-300x200.png",300,200,true],"medium_large":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2026\/03\/image-47677-768x511.png",768,511,true],"large":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2026\/03\/image-47677-800x533.png",800,533,true],"1536x1536":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2026\/03\/image-47677.png",1000,666,false],"2048x2048":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2026\/03\/image-47677.png",1000,666,false],"woocommerce_thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2026\/03\/image-47677-324x324.png",324,324,true],"woocommerce_single":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2026\/03\/image-47677-416x277.png",416,277,true],"woocommerce_gallery_thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2026\/03\/image-47677-100x100.png",100,100,true]},"uagb_author_info":{"display_name":"Sergei Voronin","author_link":"https:\/\/e-kalastus.ee\/en\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/product\/132491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/media\/132490"}],"wp:attachment":[{"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/media?parent=132491"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/product_brand?post=132491"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/product_cat?post=132491"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/e-kalastus.ee\/en\/wp-json\/wp\/v2\/product_tag?post=132491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}