{"id":14557,"date":"2023-09-02T10:46:55","date_gmt":"2023-09-02T07:46:55","guid":{"rendered":"https:\/\/e-kalastus.ee\/toode\/soot-traper-sekret-black-1kg\/"},"modified":"2026-05-08T03:01:11","modified_gmt":"2026-05-08T00:01:11","slug":"soot-traper-sekret-black-1kg","status":"publish","type":"product","link":"https:\/\/e-kalastus.ee\/toode\/soot-traper-sekret-black-1kg\/","title":{"rendered":"Peibutuss\u00f6\u00f6t Traper Sekret S\u00e4rg Black 1kg 00030"},"content":{"rendered":"\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>Toodetud valitud parima kvaliteediga looduslikest koostisosadest, lisaks termiliselt valmistatud, et saavutada parimad l\u00f5hna ja maitse omadused. Ideaalne seal, kus on suur \u00f5ngitsemissurve ja kui kalav\u00f5tt on nigel.<\/p>\n","protected":false},"featured_media":70363,"template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[1522],"product_cat":[1186],"product_tag":[],"class_list":{"0":"post-14557","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-traper","7":"product_cat-soodad","8":"pa_brand-traper","10":"first","11":"instock","12":"sale","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"uagb_featured_image_src":{"full":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/Traper-sekret-black.jpg",350,589,false],"thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/Traper-sekret-black-150x150.jpg",150,150,true],"medium":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/Traper-sekret-black-300x300.jpg",300,300,true],"medium_large":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/Traper-sekret-black-768x768.jpg",768,768,true],"large":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/Traper-sekret-black-800x800.jpg",800,800,true],"1536x1536":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/Traper-sekret-black.jpg",350,589,false],"2048x2048":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/Traper-sekret-black.jpg",350,589,false],"woocommerce_thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/Traper-sekret-black-768x768.jpg",324,324,true],"woocommerce_single":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/Traper-sekret-black.jpg",350,589,false],"woocommerce_gallery_thumbnail":["https:\/\/e-kalastus.b-cdn.net\/wp-content\/uploads\/2024\/07\/Traper-sekret-black-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"adam.mrozek","author_link":"https:\/\/e-kalastus.ee\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Toodetud valitud parima kvaliteediga looduslikest koostisosadest, lisaks termiliselt valmistatud, et saavutada parimad l\u00f5hna ja maitse omadused. Ideaalne seal, kus on suur \u00f5ngitsemissurve ja kui kalav\u00f5tt on nigel.","_links":{"self":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product\/14557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/media\/70363"}],"wp:attachment":[{"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/media?parent=14557"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product_brand?post=14557"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product_cat?post=14557"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/e-kalastus.ee\/wp-json\/wp\/v2\/product_tag?post=14557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}